{"id":1323,"date":"2012-02-05T13:06:28","date_gmt":"2012-02-05T13:06:28","guid":{"rendered":"http:\/\/www.ccconcept.ch\/CC\/?p=1323"},"modified":"2014-02-20T07:17:13","modified_gmt":"2014-02-20T07:17:13","slug":"informations-et-conseils","status":"publish","type":"post","link":"https:\/\/www.ccconcept.ch\/CC\/informations-et-conseils\/","title":{"rendered":"Informations et conseils"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1351\" title=\"iStock_000015581075Medium\" src=\"http:\/\/www.ccconcept.ch\/CC\/wp-content\/uploads\/2012\/02\/iStock_000015581075Medium-e1328450294254.jpg\" alt=\"\" width=\"280\" height=\"420\" \/><\/p>\n<h1>Tranquilisez-vous, sentez-vous bien chez vous&#8230;<\/h1>\n<p>Pour r\u00e9pondre \u00e0 la demande toujours croissante des professionnels de l&#8217;immobilier, nous avons cr\u00e9\u00e9 <span style=\"color: #ff0000;\">CC<\/span> Concept SA en 2009. Vous pouvez b\u00e9n\u00e9ficier d&#8217;une vaste gamme de produits et services aux meilleurs prix. Toutes les marques d&#8217;\u00e9lectrom\u00e9nager pour vos cuisines et buanderies.<\/p>\n<h2><a href=\"http:\/\/www.ccconcept.ch\/CC\/?page_id=29\">\u00a0M\u00e9nagez-vous, contactez-nous!<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Tranquilisez-vous, sentez-vous bien chez vous&#8230; Pour r\u00e9pondre \u00e0 la demande toujours croissante des professionnels de l&#8217;immobilier, nous avons cr\u00e9\u00e9 CC Concept SA en 2009. Vous pouvez b\u00e9n\u00e9ficier d&#8217;une vaste gamme de produits et services aux meilleurs prix. Toutes les marques d&#8217;\u00e9lectrom\u00e9nager pour vos cuisines et buanderies. \u00a0M\u00e9nagez-vous, contactez-nous!<\/p>\n","protected":false},"author":1,"featured_media":1406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[48,86],"tags":[],"class_list":["post-1323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futur","category-slider"],"_links":{"self":[{"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/posts\/1323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/comments?post=1323"}],"version-history":[{"count":5,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/posts\/1323\/revisions"}],"predecessor-version":[{"id":1924,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/posts\/1323\/revisions\/1924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/media\/1406"}],"wp:attachment":[{"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/media?parent=1323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/categories?post=1323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccconcept.ch\/CC\/wp-json\/wp\/v2\/tags?post=1323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}